{"id":2446,"date":"2022-09-18T18:28:13","date_gmt":"2022-09-18T23:28:13","guid":{"rendered":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/?post_type=product&#038;p=2446"},"modified":"2022-09-18T18:45:45","modified_gmt":"2022-09-18T23:45:45","slug":"cinta-metalizada-verde-estrellas-y-puntos-spp027-9","status":"publish","type":"product","link":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/","title":{"rendered":"Cinta Metalizada verde estrellas y puntos SPP027-9"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2451,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":{"0":"post-2446","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cinta-metalizada-m","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cinta Metalizada verde estrellas y puntos SPP027-9 - Compra al por mayor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinta Metalizada verde estrellas y puntos SPP027-9 - Compra al por mayor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/\" \/>\n<meta property=\"og:site_name\" content=\"Compra al por mayor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100064584560847&amp;locale=es_LA\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-18T23:45:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-content\/uploads\/sites\/2\/2022\/09\/SPP027-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2548\" \/>\n\t<meta property=\"og:image:height\" content=\"2548\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/product\\\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\\\/\",\"url\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/product\\\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\\\/\",\"name\":\"Cinta Metalizada verde estrellas y puntos SPP027-9 - Compra al por mayor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/product\\\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/product\\\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/SPP027-9.jpg\",\"datePublished\":\"2022-09-18T23:28:13+00:00\",\"dateModified\":\"2022-09-18T23:45:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/product\\\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/product\\\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/product\\\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/SPP027-9.jpg\",\"contentUrl\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/09\\\/SPP027-9.jpg\",\"width\":2548,\"height\":2548},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/product\\\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos al por mayor\",\"item\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cinta Metalizada verde estrellas y puntos SPP027-9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/#website\",\"url\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/\",\"name\":\"Compra al por mayor\",\"description\":\"Cintas de decorativas colcintex, compra al por mayor\",\"publisher\":{\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/#organization\",\"name\":\"Colcintex\",\"url\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/SITIO.png\",\"contentUrl\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/SITIO.png\",\"width\":350,\"height\":131,\"caption\":\"Colcintex\"},\"image\":{\"@id\":\"https:\\\/\\\/colcintex.com\\\/colcintex\\\/compra-al-por-mayor\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100064584560847&locale=es_LA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinta Metalizada verde estrellas y puntos SPP027-9 - Compra al por mayor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/","og_locale":"es_MX","og_type":"article","og_title":"Cinta Metalizada verde estrellas y puntos SPP027-9 - Compra al por mayor","og_url":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/","og_site_name":"Compra al por mayor","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100064584560847&locale=es_LA","article_modified_time":"2022-09-18T23:45:45+00:00","og_image":[{"width":2548,"height":2548,"url":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-content\/uploads\/sites\/2\/2022\/09\/SPP027-9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/","url":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/","name":"Cinta Metalizada verde estrellas y puntos SPP027-9 - Compra al por mayor","isPartOf":{"@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/#primaryimage"},"image":{"@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/#primaryimage"},"thumbnailUrl":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-content\/uploads\/sites\/2\/2022\/09\/SPP027-9.jpg","datePublished":"2022-09-18T23:28:13+00:00","dateModified":"2022-09-18T23:45:45+00:00","breadcrumb":{"@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/#primaryimage","url":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-content\/uploads\/sites\/2\/2022\/09\/SPP027-9.jpg","contentUrl":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-content\/uploads\/sites\/2\/2022\/09\/SPP027-9.jpg","width":2548,"height":2548},{"@type":"BreadcrumbList","@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/product\/cinta-metalizada-verde-estrellas-y-puntos-spp027-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/home\/"},{"@type":"ListItem","position":2,"name":"Productos al por mayor","item":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/products\/"},{"@type":"ListItem","position":3,"name":"Cinta Metalizada verde estrellas y puntos SPP027-9"}]},{"@type":"WebSite","@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/#website","url":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/","name":"Compra al por mayor","description":"Cintas de decorativas colcintex, compra al por mayor","publisher":{"@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/#organization","name":"Colcintex","url":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/#\/schema\/logo\/image\/","url":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-content\/uploads\/sites\/2\/2025\/05\/SITIO.png","contentUrl":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-content\/uploads\/sites\/2\/2025\/05\/SITIO.png","width":350,"height":131,"caption":"Colcintex"},"image":{"@id":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100064584560847&locale=es_LA"]}]}},"_links":{"self":[{"href":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-json\/wp\/v2\/product\/2446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-json\/wp\/v2\/comments?post=2446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-json\/wp\/v2\/media\/2451"}],"wp:attachment":[{"href":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-json\/wp\/v2\/media?parent=2446"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-json\/wp\/v2\/product_brand?post=2446"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-json\/wp\/v2\/product_cat?post=2446"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/colcintex.com\/colcintex\/compra-al-por-mayor\/wp-json\/wp\/v2\/product_tag?post=2446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}